{"id":256,"count":3,"description":"","link":"https:\/\/idea-intl.com\/exhibits\/category\/japan\/","name":"Exhibiting in Japan","slug":"japan","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exhibiting in Japan Archives - Idea International, Inc.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idea-intl.com\/exhibits\/category\/japan\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exhibiting in Japan Archives - Idea International, Inc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idea-intl.com\/exhibits\/category\/japan\/\" \/>\n<meta property=\"og:site_name\" content=\"Idea International, Inc.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Idea_Intl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/category\\\/japan\\\/\",\"url\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/category\\\/japan\\\/\",\"name\":\"Exhibiting in Japan Archives - Idea International, Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/category\\\/japan\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/category\\\/japan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exhibiting in Japan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/#website\",\"url\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/\",\"name\":\"Idea International, Inc.\",\"description\":\"Exhibit Design and Fabrication\",\"publisher\":{\"@id\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/#organization\",\"name\":\"Idea International, Inc.\",\"url\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/idea-international-logo300x300.png\",\"contentUrl\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/idea-international-logo300x300.png\",\"width\":300,\"height\":300,\"caption\":\"Idea International, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/idea-intl.com\\\/exhibits\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Idea.International.Inc\",\"https:\\\/\\\/x.com\\\/Idea_Intl\",\"https:\\\/\\\/www.pinterest.jp\\\/ideaintl\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/396850\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCM0lw_u2T-OK-EeZsNyp7Ag\",\"https:\\\/\\\/www.instagram.com\\\/idea_international\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exhibiting in Japan Archives - Idea International, Inc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idea-intl.com\/exhibits\/category\/japan\/","og_locale":"en_US","og_type":"article","og_title":"Exhibiting in Japan Archives - Idea International, Inc.","og_url":"https:\/\/idea-intl.com\/exhibits\/category\/japan\/","og_site_name":"Idea International, Inc.","twitter_card":"summary_large_image","twitter_site":"@Idea_Intl","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/idea-intl.com\/exhibits\/category\/japan\/","url":"https:\/\/idea-intl.com\/exhibits\/category\/japan\/","name":"Exhibiting in Japan Archives - Idea International, Inc.","isPartOf":{"@id":"https:\/\/idea-intl.com\/exhibits\/#website"},"breadcrumb":{"@id":"https:\/\/idea-intl.com\/exhibits\/category\/japan\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/idea-intl.com\/exhibits\/category\/japan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/idea-intl.com\/exhibits\/"},{"@type":"ListItem","position":2,"name":"Exhibiting in Japan"}]},{"@type":"WebSite","@id":"https:\/\/idea-intl.com\/exhibits\/#website","url":"https:\/\/idea-intl.com\/exhibits\/","name":"Idea International, Inc.","description":"Exhibit Design and Fabrication","publisher":{"@id":"https:\/\/idea-intl.com\/exhibits\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idea-intl.com\/exhibits\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/idea-intl.com\/exhibits\/#organization","name":"Idea International, Inc.","url":"https:\/\/idea-intl.com\/exhibits\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/idea-intl.com\/exhibits\/#\/schema\/logo\/image\/","url":"https:\/\/idea-intl.com\/exhibits\/wp-content\/uploads\/2018\/04\/idea-international-logo300x300.png","contentUrl":"https:\/\/idea-intl.com\/exhibits\/wp-content\/uploads\/2018\/04\/idea-international-logo300x300.png","width":300,"height":300,"caption":"Idea International, Inc."},"image":{"@id":"https:\/\/idea-intl.com\/exhibits\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Idea.International.Inc","https:\/\/x.com\/Idea_Intl","https:\/\/www.pinterest.jp\/ideaintl\/","https:\/\/www.linkedin.com\/company\/396850","https:\/\/www.youtube.com\/channel\/UCM0lw_u2T-OK-EeZsNyp7Ag","https:\/\/www.instagram.com\/idea_international\/"]}]}},"lang":"en","translations":{"en":256,"ja":485},"_links":{"self":[{"href":"https:\/\/idea-intl.com\/exhibits\/wp-json\/wp\/v2\/categories\/256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idea-intl.com\/exhibits\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/idea-intl.com\/exhibits\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/idea-intl.com\/exhibits\/wp-json\/wp\/v2\/posts?categories=256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}